{"id":6612,"date":"2024-06-27T12:46:37","date_gmt":"2024-06-27T12:46:37","guid":{"rendered":"https:\/\/eudailytimes.com\/la-russia-non-tocchi-i-confini-sul-mar-baltico-unione-europea-e-nato-reagiscano\/"},"modified":"2024-06-27T12:46:37","modified_gmt":"2024-06-27T12:46:37","slug":"la-russia-non-tocchi-i-confini-sul-mar-baltico-unione-europea-e-nato-reagiscano","status":"publish","type":"post","link":"https:\/\/eudailytimes.com\/it\/la-russia-non-tocchi-i-confini-sul-mar-baltico-unione-europea-e-nato-reagiscano\/","title":{"rendered":"\u00abLa Russia non tocchi i confini sul mar Baltico. Unione Europea e Nato reagiscano\u00bb"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"m16621-16620-16622\">\n<p class=\"chapter-paragraph\"><b>La mossa della Duma \u00e8 una provocazione?\u00a0<\/b><br \/>\u00abStiamo cercando di stabilire quali sono le reali intenzioni. I Paesi coinvolti sarebbero non solo i due citati nel comunicato diffuso dalla Duma mercoled\u00ec, la Lituania e la Finlandia; se la Russia decidesse di cambiare unilateralmente i confini marittimi, anche Estonia, Svezia e Polonia sarebbero coinvolte\u00bb.\u00a0<\/p>\n<\/div>\n<div id=\"m16631-16630-16632\">\n<p class=\"chapter-paragraph\"><b>Perch\u00e9 allora hanno citato solo voi e i finlandesi?<\/b>\u00a0<br \/>\u00abDifficile dirlo. In Lituania siamo in una settimana elettorale, ogni tema diventa molto caldo. Siamo di fronte a un tentativo deliberato di seminare confusione&#8230;<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.corriere.it\/esteri\/24_maggio_24\/intervista-ministro-degli-esteri-lituano-landsbergis-b40bacac-db84-4459-8890-4795dfc4bxlk_amp.shtml\">Fonte<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mossa della Duma \u00e8 una provocazione?\u00a0\u00abStiamo cercando di stabilire quali sono le reali intenzioni. I Paesi coinvolti sarebbero non solo i due citati nel comunicato diffuso dalla Duma mercoled\u00ec, la Lituania e la Finlandia; se la Russia decidesse di cambiare unilateralmente i confini marittimi, anche Estonia, Svezia e Polonia sarebbero coinvolte\u00bb.\u00a0 Perch\u00e9 allora hanno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[529],"tags":[],"class_list":["post-6612","post","type-post","status-publish","format-standard","hentry","category-lituania"],"_links":{"self":[{"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/posts\/6612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/comments?post=6612"}],"version-history":[{"count":0,"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/posts\/6612\/revisions"}],"wp:attachment":[{"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/media?parent=6612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/categories?post=6612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eudailytimes.com\/it\/wp-json\/wp\/v2\/tags?post=6612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}